{"id":2848,"date":"2021-03-16T22:54:34","date_gmt":"2021-03-17T02:54:34","guid":{"rendered":"http:\/\/revistajuridica.uprrp.edu\/inrev\/?p=2848"},"modified":"2021-03-16T22:54:34","modified_gmt":"2021-03-17T02:54:34","slug":"resenas-del-simposio-retos-de-la-democracia-puertorriquena","status":"publish","type":"post","link":"https:\/\/derecho.uprrp.edu\/inrev\/2021\/03\/16\/resenas-del-simposio-retos-de-la-democracia-puertorriquena\/","title":{"rendered":"Rese\u00f1a del Simposio: Retos de la democracia puertorrique\u00f1a | Primer Panel"},"content":{"rendered":"\n\t\t\t\t\n<h2 class=\"has-text-align-center wp-block-heading\">Primer panel: Estado de la democracia, perspectiva global <\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>RESE\u00d1A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por: Giuliana Gonz\u00e1lez Espino*<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Revista Jur\u00eddica de la Universidad de Puerto Rico llev\u00f3 a cabo el pasado 16 de febrero de 2021, el simposio virtual:&nbsp;<em>Retos de la democracia puertorrique\u00f1a<\/em>, el cual se dividi\u00f3 en conferencias de tres d\u00edas cada una con su respectivo panel de invitados. La primera conferencia, la cual se resume en esta rese\u00f1a, estuvo dedicada al estado de la democracia desde una perspectiva global. Este panel cont\u00f3 con la participaci\u00f3n de la licenciada y exjueza Sonia I. V\u00e9lez Col\u00f3n como moderadora. Los panelistas invitados fueron la profesora y Decana de Asuntos Acad\u00e9micos de la Escuela de Derecho de la Universidad Interamericana de Puerto Rico, la Lcda. Yanira Reyes Gil, el director del Centro de Derecho P\u00fablico de Nueva Zelanda y profesor de la Facultad de Derecho de la Universidad de Victoria en Wellington en Nueva Zelanda, el Lcdo.&nbsp;Joel I. Col\u00f3n R\u00edos y el profesor Catedr\u00e1tico de la Escuela de Derecho de la Universidad de Puerto Rico, el Lcdo. Luis E. Rodr\u00edguez Rivera.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Retos de la democracia puertorrique\u00f1a: Estado de la democracia perspectiva global<\/em>, comenz\u00f3 con una ponencia a cargo del profesor Joel I. Col\u00f3n R\u00edos. Col\u00f3n R\u00edos destac\u00f3 ciertas problem\u00e1ticas que ha enfrentado la democracia globalmente. Posteriormente Rodr\u00edguez Rivera y Reyes Gil ofrecieron sus comentarios y reacciones al respecto. Adem\u00e1s, el panel brind\u00f3 espacio para que los invitados atendieran una serie de interrogantes que permitieron profundizar temas de inter\u00e9s para los y las estudiantes de la Escuela de Derecho que conforman el Cuerpo Editorial de la Revista Jur\u00eddica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Ponencia de Joel I. Col\u00f3n R\u00edos:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Col\u00f3n R\u00edos le dio apertura a la discusi\u00f3n de su ponencia se\u00f1alando la importancia de reflexionar acerca de la democracia desde una perspectiva global. Col\u00f3n R\u00edos destac\u00f3 tres problemas que se han venido acentuando en las pasadas d\u00e9cadas: (1) Falta de representatividad, (2) Tendencia hacia la oligarqu\u00eda; y (3) Presencia de un d\u00e9ficit de participaci\u00f3n. Hizo alusi\u00f3n al profesor y autor Colin Crouch, cuando mencion\u00f3 el concepto de&nbsp;<em>posdemocracia<\/em>&nbsp;para describir lo que entiende es un \u201cdesequilibrio entre grandes conglomerados econ\u00f3micos o corporativos y dem\u00e1s grupos sociales\u201d. Se\u00f1al\u00f3 que la pol\u00edtica, desde esa perspectiva, se considera \u201cun asunto de las \u00e9lites\u201d.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cNos hemos ido moviendo a lo antidemocr\u00e1tico cada vez m\u00e1s y m\u00e1s.\u201d<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00edos expres\u00f3 que lo que se considera como&nbsp;<em>democratcic backsliding<\/em>&nbsp;se refiere a cuando los gobiernos formalmente democr\u00e1ticos proceden a debilitar o eliminar elementos que se consideran esenciales para el funcionamiento de la democracia, lo que se puede evidenciar a trav\u00e9s del funcionamiento del poder judicial y un sistema electoral justo. Por tal raz\u00f3n, Col\u00f3n R\u00edos destac\u00f3 que se ha recurrido a reformas constitucionales con la intenci\u00f3n de proteger la democracia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los gobiernos&nbsp;\u2018populistas\u2019&nbsp;se han multiplicado y los an\u00e1lisis acad\u00e9micos relacionados al mismo, a su vez, se han multiplicado. En la mayor\u00eda de los casos, las transformaciones del autoritarismo \u2014algunas m\u00e1s leves y otras&nbsp;m\u00e1s&nbsp;serias\u2014 se presentan por sus defensores como&nbsp;reivindicaciones&nbsp;bajo el liderato de una figura carism\u00e1tica que busca \u201cproteger los verdaderos intereses del pueblo\u201d. Se le podr\u00eda dar un enfoque a simplemente denunciarlo, es decir, denunciar los efectos tributarios, la xenofobia y los efectos perjudiciales al medio ambiente. Sin embargo, el profesor Joel Col\u00f3n&nbsp;enfatiz\u00f3&nbsp;los reclamos no infundados en grupos que tienden a favorecer gobiernos autoritarios o populistas. Se\u00f1al\u00f3 que este problema se ha ido acentuado durante las&nbsp;\u00faltimas&nbsp;d\u00e9cadas y que no es un asunto&nbsp;nuevo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar la introducci\u00f3n de la ponencia, el profesor Joel Col\u00f3n procedi\u00f3 a explicar los tres problemas mencionados anteriormente, comenzando con la falta de representatividad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comenz\u00f3 explicando que antes de la consolidaci\u00f3n de la democracia representativa moderna, los individuos electos a parlamento o asamblea legislativa se entend\u00edan vinculados a las instrucciones de aquellos que los eligieron. Suced\u00eda as\u00ed porque eran grupos m\u00e1s peque\u00f1os al excluir a mujeres, negros, pobres, entre otras minor\u00edas. En la pr\u00e1ctica, las instrucciones vinculantes o el mandato imperativo quer\u00edan decir que los legisladores se encontraban obligados a votar de determinada manera dependiendo de lo que establecieran las instrucciones recibidas al momento de su elecci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los primeros reclamos en la Revoluci\u00f3n Francesa fue la eliminaci\u00f3n de los mandatos imperativos&nbsp;porque si los delegados a la asamblea legislativa hubiesen seguido estrictamente sus instrucciones, no hubiesen podido lograr lo que se logr\u00f3 en la Revoluci\u00f3n Francesa. Aquellos que s\u00ed&nbsp;favorecieron&nbsp;el mandato imperativo, pero tambi\u00e9n estaban de acuerdo con la Revoluci\u00f3n Francesa, insist\u00edan en que la abolici\u00f3n al mandato dar\u00eda lugar a una casta pol\u00edtica cuya prioridad ser\u00eda proteger sus propios intereses y no los de los electores. Esto es lo que ha venido sucediendo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La idea de que las legislaturas en \u00faltima instancia no representan al pueblo, no parece estar tan alejada de la realidad. Las actuaciones de los miembros parecen ser guiadas por preocupaciones relacionadas a intereses partidistas, el balance de poder en la&nbsp;Asamblea&nbsp;Legislativa o intereses de grupos econ\u00f3micos, resultando en corrupci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Expres\u00f3 que este&nbsp;\u00faltimo punto est\u00e1 directamente relacionado con el segundo, que es la tendencia hacia la oligarqu\u00eda. A modo de ejemplo, el profesor Col\u00f3n R\u00edos mencion\u00f3 y defini\u00f3 la pol\u00edtica de Arist\u00f3teles al explicar que la misma buscaba el bien de todos los miembros de la sociedad. Arist\u00f3teles le llam\u00f3 oligarqu\u00eda a la degeneraci\u00f3n de la aristocracia, es decir, la \u00e9lite econ\u00f3mica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad a nivel global existe una brecha extensa entre los m\u00e1s ricos y los m\u00e1s pobres. Por ejemplo, en los Estados Unidos el 1% m\u00e1s rico posee el 40% de las riquezas, y los individuos que componen las ramas de gobierno componen el 2% m\u00e1s rico. La democracia parece acercarse cada vez m\u00e1s a una oligarqu\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos primeros dos problemas \u2014falta de representatividad y la tendencia hacia la oligarqu\u00eda\u2014 van de la mano con el tercer problema se\u00f1alado por Col\u00f3n R\u00edos, que es el d\u00e9ficit de representaci\u00f3n. El tercer problema con respecto al d\u00e9ficit tiene un aspecto formal y uno informal. Existe un convencimiento de que independientemente como voten, las decisiones gubernamentales no responder\u00e1n ni a la voluntad, ni a los intereses de la mayor\u00eda. Los sistemas gubernamentales olig\u00e1rquicos no son compatibles con el aspecto formal. Los tres factores no son s\u00edntomas presentes en jurisdicciones en particular, sino que aplica a los sistemas democr\u00e1ticos de forma general.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Col\u00f3n R\u00edos se\u00f1al\u00f3&nbsp;que no cabe hablar de un&nbsp;<em>demos<\/em>&nbsp;o pueblo.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEl primer paso es reconocer que el triunfo de partidos de derecha es una respuesta no democr\u00e1tica a esa crisis. Pol\u00edticos&nbsp;\u2018populistas\u2019&nbsp;han sido exitosos y prevalecen por esta misma raz\u00f3n.\u201d&nbsp;<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Destaca que la soluci\u00f3n que el presidente Trump en Estados Unidos o el presidente Bolsonaro en Brasil brindaron a ese problema no&nbsp;estuvo&nbsp;dirigida a aumentar la representatividad de instituciones ni eliminar tendencias olig\u00e1rquicas. La tarea del resto es desarrollar una propuesta democr\u00e1tica. No puede ser una respuesta que simplemente busque regresar a lo de antes, porque ese estado de cosas ya conten\u00eda los g\u00e9rmenes de la crisis que vivimos. Prevalecen el aspecto necesario de repensar la instituci\u00f3n democr\u00e1tica para complementarla con mecanismos que sirvan como medios para&nbsp;<em>aumentar<\/em>&nbsp;la representatividad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A modo de conclusi\u00f3n a su ponencia, el profesor Col\u00f3n R\u00edos, recomend\u00f3 un regreso parcial al mandato imperativo y pensar seriamente en participaci\u00f3n novedosa como, por ejemplo, a trav\u00e9s de las asambleas de ciudadanos elegidos aleatoriamente y asambleas locales con poderes decisionales sustanciales. Con respecto a lo pol\u00edtico, los movimientos tendr\u00edan que acceder al poder a trav\u00e9s de sistemas electorales existentes o lograr ejercer presiones suficientes para lograr la adopci\u00f3n de esos mecanismos. Se\u00f1al\u00f3&nbsp;que quiz\u00e1s haya que aprender algo del populismo.&nbsp;Refiri\u00e9ndose a&nbsp;aceptar que los intereses del pueblo son distintos a los que est\u00e1n en el poder. Es importante entender al pueblo como un grupo de seres humanos con pluralidad de reclamos ante la justicia social, violencia de g\u00e9nero, derechos de los pensionados, entre otros. Desde esta perspectiva, la tarea ser\u00eda identificar y hacer expl\u00edcito aquello que une a estos grupos y en efecto,&nbsp;reemplazar&nbsp;a la casta pol\u00edtica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al culminar la ponencia, la moderadora Sonia V\u00e9lez Col\u00f3n abri\u00f3 los turnos de comentarios para permitir la reacci\u00f3n de Yanira Reyes Gil y Luis E. Rodr\u00edguez&nbsp;Rivera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Reacci\u00f3n de Yanira Reyes Gil:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reyes Gil destac\u00f3 que hay fen\u00f3menos que identific\u00f3&nbsp;Col\u00f3n R\u00edos&nbsp;los cuales son&nbsp;indicativos de&nbsp;problem\u00e1ticas&nbsp;que han tenido las democracias modernas para incluir ese ideal democr\u00e1tico. Sobre el d\u00e9ficit de participaci\u00f3n, la decana y profesora se\u00f1al\u00f3 que:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la crisis de la democracia, la profesora menciona el&nbsp;<em>democratic backsliding<\/em>&nbsp;y explic\u00f3&nbsp;que son situaciones en las que el gobierno formalmente democr\u00e1tico&nbsp;procede&nbsp;a debilitar o eliminar elementos que se consideran esenciales para el funcionamiento de una democracia como independencia judicial o sistema electoral justo). En este caso la profesora lo relacion\u00f3&nbsp;con la Junta de Control Fiscal y mencion\u00f3&nbsp;que en t\u00e9rminos de derechos civiles y pol\u00edticos significa una disminuci\u00f3n de derechos.&nbsp;\u201cRepresenta la eliminaci\u00f3n de derechos sociales y econ\u00f3micos cuando hablamos de medidas de austeridad&nbsp;[que atacan medidas de primera necesidad como educaci\u00f3n, salud, alimentaci\u00f3n, trabajo, vivienda].\u201d&nbsp;El segundo problema que mencion\u00f3&nbsp;y explic\u00f3&nbsp;Reyes Gil&nbsp;fueacerca del ascenso de los gobiernos autoritarios con respecto a la incapacidad de los gobiernos que generalmente se describen como democr\u00e1ticos en promover los intereses de las mayor\u00edas populares. Destac\u00f3&nbsp;el ascenso de grupos fundamentalistas a espacios de poder en el gobierno de Puerto Rico, Estados Unidos y todas partes del mundo.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cMuchas de las acciones u agresiones son dirigidas hacia mujeres y comunidades LGBTTQIA+ y esto a su vez provoca que grupos feministas y de la sociedad&nbsp;civil se&nbsp;activen para defender derechos que ya ten\u00edan. Las religiones y el derecho comparten su discurso de control y de orden.\u201d&nbsp;&nbsp;A modo de expandir la conversaci\u00f3n, cit\u00f3 al Reverendo Rivera Pag\u00e1n al decir que \u201cel fundamentalismo cristiano naci\u00f3 dentro de la naci\u00f3n evang\u00e9lica estadounidense como un rechazo a m\u00faltiples cambios culturales que sectores religiosos conservadores catalogaron&nbsp;como secularismo y alejamiento de las normas sociales ordenadas por Dios. Los fundamentalistas se perciben como guerreros de la fe cruzados del cristianismo evang\u00e9lico ortodoxo.\u201d<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Este asunto de fortalecimiento de los sectores religiosos fundamentalistas atados a grupos conservadores se ven relacionados al presidente Trump y al presidente Bolsonaro. La panelista destac\u00f3 que varios movimientos por parte del presidente Trump para negar derechos a minor\u00edas&nbsp;\u00e9tnicas&nbsp;y tambi\u00e9n derechos sexuales y reproductivos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reyes Gil reafirm\u00f3 el d\u00e9ficit de participaci\u00f3n como un problema de los estados modernos de democracia. Mencion\u00f3 el&nbsp;<em>Verano del \u201919<\/em>&nbsp;y lo relacion\u00f3 con la participaci\u00f3n formal institucional porque lo que se demostr\u00f3 durante el proceso fue la participaci\u00f3n directa de Puerto Rico a trav\u00e9s del reclamo de renuncia sin antes acudir a remedios legales. Sirvi\u00f3 como movimiento pol\u00edtico social que intent\u00f3 forzar a las instituciones a reconocer espacios democr\u00e1ticos. Por ejemplo, la Asamblea Legislativa se vio obligada a iniciar el proceso de residenciamiento porque estaba pasando ya una movilizaci\u00f3n y por otro lado el Colegio de Abogados igualmente inici\u00f3 su propio proceso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que la lectura de la Constituci\u00f3n de Puerto Rico en la Fortaleza sirvi\u00f3 como un reflejo de acci\u00f3n directa. Hizo hincapi\u00e9 en la interrogante que circulaba en los medios en el momento: \u201c\u00bfSi la legislatura no lo residencia, podemos votar para restituirlo?\u201d La Constituci\u00f3n no provee para ello. Parte de lo que se ha planteado sobre el&nbsp;<em>Verano del 19\u2019<\/em>&nbsp;es ver las experiencias de otros pa\u00edses, especialmente movimientos latinoamericanos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Reacci\u00f3n de Luis E. Rodr\u00edguez&nbsp;<\/em><\/strong><strong><em>Rivera:<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;catedr\u00e1tico&nbsp;comenz\u00f3 su turno resaltando el enfoque&nbsp;y el&nbsp;rol del derecho internacional en el decaimiento en la democracia. Expres\u00f3 que existen dos periodos distintos importantes: Antes del 1989 y despu\u00e9s de la ca\u00edda del Muro de Berl\u00edn. Rodr\u00edguez Rivera coment\u00f3 que antes se entend\u00eda que el derecho internacional p\u00fablico era agn\u00f3stico en cuanto al tipo y la forma de gobierno de la democracia y no se atend\u00eda realmente porque era jurisdicci\u00f3n de los estados o asuntos internos que se trataban dentro del derecho constitucional nacional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, resalt\u00f3 dos excepciones. Despu\u00e9s de la Segunda Guerra Mundial, la comunidad internacional aprob\u00f3 la prohibici\u00f3n de sistemas que inherentemente&nbsp;engendraron&nbsp;desigualdad e interpuso los&nbsp;l\u00edmites&nbsp;a poderes nacionales de gobernanza que surgieron por la creaci\u00f3n de los Derechos Humanos. Lo dem\u00e1s se entend\u00eda que quedaba bajo jurisdicci\u00f3n de cada naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se emitieron resoluciones por parte de las Naciones Unidas y otras organizaciones regionales que promovieron el derecho a la democracia y que se&nbsp;enfocaron&nbsp;en el concepto de las elecciones libres y justas. Se impusieron a su vez, sanciones del Fondo Monetario Internacional, Banco Mundial de Fomento, entre otras instituciones internacionales. Adem\u00e1s, surgieron decenas de levantamientos de protestas en distintas partes del mundo reflejadas en las normas consuetudinarias emergentes y todas enfocadas en el aspecto procesal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, el profesor Rodr\u00edguez inici\u00f3 una discusi\u00f3n cr\u00edtica sobre la democracia: en conjunto con la comunidad internacional y las promesas incumplidas desde el 1989. Se\u00f1al\u00f3 que muchas de las intervenciones&nbsp;para establecer democracia se&nbsp;hicieron&nbsp;para convertirse en estados semi-autoritarios donde no hab\u00eda&nbsp;un compromiso legal, pero que&nbsp;actualmente&nbsp;lo que vemos es que se ha perpetuado condiciones de extremismo y conflicto. Rodr\u00edguez Rivera&nbsp;ofreci\u00f3 como ejemplo las protestas de Hait\u00ed para remover al presidente actual.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 tambi\u00e9n la importancia del impacto imperialista de democratizaci\u00f3n&nbsp;del derecho&nbsp;internacional y como se utiliza la gobernanza democr\u00e1tica como base legal para justificar cambios de r\u00e9gimen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El panelista se\u00f1al\u00f3 que la democracia es mucho m\u00e1s que las elecciones. Col\u00f3n resalt\u00f3 tambi\u00e9n que en las \u00faltimas d\u00e9cadas ha habido un aumento de violaciones a los Derechos Humanos por parte de democracias leg\u00edtimas post ataques terroristas a ra\u00edz del 9\/11.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mencion\u00f3 que existe una relaci\u00f3n entre la democracia y el neoliberalismo. El neoliberalismo busca proteger intereses econ\u00f3micos en el mercado libre&nbsp;y&nbsp;para lograr esto, establecen par\u00e1metros que colocan el crecimiento de la inversi\u00f3n, ganancia y la propiedad, fuera del alcance pol\u00edtico de los ciudadanos.&nbsp;Mientras que otras alternativas para organizar la vida colectiva son sistem\u00e1ticamente obstruidas por esta gobernanza democr\u00e1tica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parece representativa, pero \u00bfqu\u00e9 realmente representa? Representa una forma particular de la sociedad y pol\u00edticas&nbsp;p\u00fablicas&nbsp;que promueven el capitalismo neoliberal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00daltima reacci\u00f3n Joel I. Col\u00f3n R<\/em><\/strong><strong><em>\u00edos:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su intervenci\u00f3n indic\u00f3 que era interesante poner en perspectiva internacional la decadencia de la democracia y&nbsp;mencion\u00f3&nbsp;que el derecho internacional se percibe como el ejemplo a seguir. Por tanto se tiende a comparar con el derecho municipal o estatal de cada jurisdicci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ra\u00edz de las preguntas&nbsp;<em>realizadas por el Cuerpo Editorial de la Revista Jur\u00eddica, los panelistas tuvieron la oportunidad de profundizar en ciertos temas relacionados al estado de la democracia global. A continuaci\u00f3n, las preguntas presentadas al panel:&nbsp;<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\" type=\"1\"><li><strong>La figura de Donald Trump tuvo un impacto significativo a nivel nacional e internacional&nbsp;y&nbsp;aval\u00f3 candidaturas de otros pa\u00edses que eran conservadoras. \u00bfCu\u00e1l ha sido el impacto de la presidencia de Donald Trump&nbsp;en&nbsp;la democracia estadounidense y a nivel mundial? \u00bfPiensan ustedes que el presidente Trump marc\u00f3 en alguna manera un ascenso de la ultraderecha?<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Joel I. Col\u00f3n R\u00edos:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Col\u00f3n R\u00edos destac\u00f3 que no&nbsp;se le debe dar tanto cr\u00e9dito a Trump. Representa un fen\u00f3meno similar a lo que ocurre con Bolsonaro en Brasil. Destac\u00f3&nbsp;que la pregunta interesante es: \u00bfQu\u00e9 es lo que hace posible que ellos hayan llegado al poder y generado todo ese impacto?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump y Bolsonaro han articulado un problema que permite que aquellos que han perdido su trabajo o que sienten que no tienen suficiente dinero para sustentar a sus familias, se comiencen a ver como un ente pol\u00edtico como pueblo que tiene que enfrentar algo. Grandes sectores de la poblaci\u00f3n est\u00e1n esperando a que haya respuestas a problemas que siguen estando presentes en ciclos electorales. Lo que une a todas las figuras ultraderecha es que supieron reconocer un problema, pero dar una respuesta antidemocr\u00e1tica al problema.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Yanira Gil Reyes:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fen\u00f3meno no es nuevo ni surgi\u00f3 en los&nbsp;2000&#8217;s, viene de antes y se ha podido ver en distintos momentos, pero por etapas. Tiene que ver con surgimiento de movimientos progresistas o de izquierda y entonces se produce una reacci\u00f3n m\u00e1s conservadora.&nbsp;Reyes Gil establece que hay una diferenciaci\u00f3n,&nbsp;que no todos los movimientos de ultraderecha son iguales. Algunos de esos movimientos participaron&nbsp;de procesos constitucionales&nbsp;y democr\u00e1tico, pero hay&nbsp;otros&nbsp;que son m\u00e1s extremos y que ni siquiera reconocen las instituciones. Se consideran como&nbsp;<em>anti-establishment<\/em>. No nos tenemos que centrar \u00fanicamente&nbsp;en los gobernantes. Bolsonaro y Trump no llegaron al poder solos. Recibieron mucho apoyo. Es importante reconocer los grupos que impulsan esas candidaturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Luis E. Rodr\u00edguez Rivera:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante el decaimiento de la gobernanza democr\u00e1tica y aumento de pobreza e inequidad, cuando se presenta alternativa que ret\u00f3rica es distinta, ah\u00ed es que suben al poder. Pero, el desencanto por ellos tambi\u00e9n ocurre porque ellos no est\u00e1n para provocar un cambio, sino para beneficiarse a ellos mismos. El gobierno es para buscar soluciones y velar por los intereses del pueblo. Hasta que eso no ocurra, seguir\u00e1 el vaiv\u00e9n continuo.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>El 6 de enero y luego de que Biden asumiera la presidencia. Se&nbsp;contempl\u00f3&nbsp;un proceso bajo la enmienda 25&nbsp;de la Constituci\u00f3n&nbsp;Federal que ten\u00eda que ser activada por el vicepresidente, o iniciar el residenciamiento. Sabemos que ninguna de las dos se activ\u00f3. \u00bfC\u00f3mo y en qu\u00e9 forma consideran ustedes que esto ha afectado la visi\u00f3n y percepci\u00f3n global que tiene el mundo de EE. UU. cuando adoptaron y escogieron esta medida que finalmente fue derrotada en el Congreso? \u00bfTiene esto alguna implicaci\u00f3n para la democracia estadounidense? \u00bfEn qu\u00e9&nbsp;posici\u00f3n coloca esto al presidente Biden con la figura compleja de cara a una presidencia no muy prolongada y&nbsp;qu\u00e9&nbsp;rol podr\u00eda asumir la presidenta Harris ante los asuntos diplom\u00e1ticos?&nbsp;<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Joel I. Col\u00f3n R<\/em><\/strong><strong><em>\u00edos:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En t\u00e9rminos de percepci\u00f3n global, el proceso de residenciamiento le a\u00f1ade a lo que es una percepci\u00f3n m\u00e1s negativa de Estados Unidos. Ante el mundo en t\u00e9rminos de ejemplo. Es dif\u00edcil usarlo como referente principal. En t\u00e9rminos de democracia y el efecto interno como pa\u00eds, ha habido en Am\u00e9rica Latina y globalmente, un aumento en la utilizaci\u00f3n del residenciamiento para remover gobernantes, como, por ejemplo, Brasil y Paraguay. En ambos lo que se trat\u00f3 fue de residenciar a un presidente no de ultraderecha, pero de izquierdas progresistas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El riesgo para Estados Unidos o para el sistema presidencial es que, en un clima de polarizaci\u00f3n pol\u00edtica, uno tiene que estar consciente de que lo que uno hace hoy, se lo pueden hacer ma\u00f1ana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Yanira Reyes Gil:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3&nbsp;que un enfoque que se le puede dar a la pregunta es que el residenciamiento iba a poner en peligro la visi\u00f3n global de los Estados Unidos. Pero la panelista expres\u00f3, que, si se hubiera llevado a cabo un proceso razonable del residenciamiento, en lugar de estar afectado por asuntos partidistas, eso precisamente hubiera ayudado a mejorar la percepci\u00f3n global que tiene el mundo ante los Estados Unidos.&nbsp;&nbsp;Se puede marcar un antes y un despu\u00e9s de la presidencia de Trump.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cYa ese mito de que Estados Unidos es el referente principal de la democracia qued\u00f3 destronado\u201d, reafirm\u00f3 Reyes Gil.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Los actos del 6 de enero pusieron en perspectiva como el resto de los pa\u00edses ven a Estados Unidos. La respuesta del Estado es importante tambi\u00e9n en&nbsp;c\u00f3mo&nbsp;el mundo mira a los Estados Unidos. Si responde razonablemente o por otro si no responde a infracciones de Trump, eso lacera&nbsp;a\u00fan&nbsp;m\u00e1s la percepci\u00f3n. Se ten\u00eda una visi\u00f3n c\u00ednica de&nbsp;c\u00f3mo&nbsp;el Senado iba a responder ante el residenciamiento. La gran polarizaci\u00f3n provoca y obliga a que ciertos sectores asuman posturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Luis E. Rodr\u00edguez Rivera:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La globalizaci\u00f3n lo que busca es estabilidad en los Estados. El fen\u00f3meno de Trump que no quer\u00eda llevar a cabo una transici\u00f3n pac\u00edfica presentaba una potencial de inestabilidad que los mercados no quieren tomar. La movida de intentar levantar distintas teor\u00edas para sacar del poder al presidente Trump era como un juego de p\u00f3quer y una estrategia pol\u00edtica m\u00e1s.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>La crisis que ha provocado el Covid-19 ha trastocado la salud p\u00fablica y tambi\u00e9n ha creado una crisis econ\u00f3mica que incluso se hace evidente en Puerto Rico y a nivel mundial. Brasil y Estados Unidos tienen las tasas m\u00e1s altas de muertes y son un reflejo de&nbsp;<\/strong><strong>c\u00f3mo&nbsp;ambas crisis se han visto reflejadas en el manejo del gobierno de derecha. Estad\u00edsticas demuestran que la popularidad de estos gobernantes ha deca\u00eddo a causa de esto. \u00bfEn qu\u00e9 manera las ideolog\u00edas y medidas de un gobierno pueden provocar o evitar una crisis salubrista, institucional y econ\u00f3mica? \u00bfC\u00f3mo ustedes que se han comportado los llamados gobiernos democr\u00e1ticos versus otros sistemas de gobiernos mucho m\u00e1s conservadores a la hora de enfrentarse a la crisis ocasionada por la pandemia?&nbsp;<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Joel I. Col\u00f3n R<\/em><\/strong><strong><em>\u00edos:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ideolog\u00edas y pol\u00edticas p\u00fablicas pueden crear crisis de todo tipo y m\u00e1s todav\u00eda salubristas. Medidas de austeridad en sistemas de salud p\u00fablica puede provocar crisis de salud p\u00fablica. El&nbsp;cuarenta por ciento&nbsp;de las muertes en Estados Unidos se pudieron haber evitado si se hubiesen tomado las medidas pertinentes. La crisis de salud p\u00fablica no solamente pueden ser el efecto de medidas tomadas por el gobierno, tambi\u00e9n pueden provocar cambios ideol\u00f3gicos, institucionales y econ\u00f3micos. Se puede movilizar la organizaci\u00f3n pol\u00edtica a trav\u00e9s de medios electr\u00f3nicos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Yanira Reyes Gil:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La panelista estableci\u00f3 que afecta todo tipo de manejo de las emergencias, en este caso la pandemia,&nbsp;pero de igual&nbsp;forma se puede hablar del Hurac\u00e1n Mar\u00eda. En Puerto Rico, la reacci\u00f3n del Estado ha sido reprimir en vez de proteger como tener mayor acceso a educaci\u00f3n salubrista, pruebas y medicamentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Luis E. Rodr\u00edguez Rivera:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando tienes una ideolog\u00eda pol\u00edtica que da prioridad a la econom\u00eda sobre las vidas y que trata una crisis humana bajo an\u00e1lisis de manejo de riesgo, [esta]va a abonar&nbsp;al desgaste&nbsp;de la democracia.&nbsp;&nbsp;Desde la perspectiva de Rodr\u00edguez, definitivamente se pudo haber evitado la crisis.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Parte del hecho de que recientemente pa\u00edses como&nbsp;<\/strong><strong>Argentina&nbsp;que es un pa\u00eds tradicionalmente religioso se han adoptado medidas y aprobado leyes que en cierto sentido trastocan esos ideales que grupos religiosos valoran. Argentina acaba de legalizar el aborto. Sin embargo, tambi\u00e9n hay otros pa\u00edses como India e Israel que han tomado acercamientos opuestos y se han convertido en pa\u00edses m\u00e1s seculares. \u00bfCu\u00e1l cree usted que es la ra\u00edz de este fen\u00f3meno? \u00bfEs contradictorio? \u00bfEl mundo se comunica o no?<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Yanira Reyes Gil:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El asunto de la marea feminista que arrop\u00f3 a Latinoam\u00e9rica se debi\u00f3 a que se estaba trabajando con derechos sexuales y reproductivos de las mujeres en esos pa\u00edses. La profesora indic\u00f3 que bajo su perspectiva no es contradictorio porque se pueden observar unas altas y bajas en el desarrollo y en las conquistas. Lo&nbsp;contradictorio es&nbsp;que cuando hay avances, viene entonces un&nbsp;<em>backlash&nbsp;<\/em>conservador que trata de limitar los derechos. Argentina tard\u00f3 mucho tiempo para lograr esto, pero tambi\u00e9n tuvo que ver con el apoyo a nivel mundial. En Chile recientemente el pa\u00eds vot\u00f3 por cambiar su constituci\u00f3n y que fuera una paritaria en la que hubiera igual participaci\u00f3n de las mujeres.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Con el paso del tiempo se ha visto como los niveles de contaminaci\u00f3n va en incremento. Actualmente se est\u00e1 atravesando una crisis con el reciclaje de pl\u00e1sticos donde pa\u00edses como China e Indonesia sus costas est\u00e1n inundadas de pl\u00e1sticos. \u00bfCree usted que tenemos un derecho humano al ambiente que nos rodea?&nbsp;<\/strong><strong>\u00bfSer\u00e1n&nbsp;las acciones que&nbsp;han tomado&nbsp;algunas industrias como, por ejemplo, Coca Cola, para reducir pl\u00e1stico y reciclar el 100% de sus empaques hasta el 2030 sea suficiente? \u00bfQu\u00e9 papel cree usted que juega la educaci\u00f3n?<\/strong><em><\/em><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Luis&nbsp;<\/em><\/strong><strong><em>E. Rodr\u00edguez Rivera:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed existe un derecho humano al medio ambiente. Los estados han reconocido de forma expl\u00edcita e impl\u00edcita ante este derecho. La pregunta es \u00bfPor qu\u00e9 entonces esos mismos estados diariamente violan el marco jur\u00eddico a favor del ambiente? Hay unos obst\u00e1culos sist\u00e9micos inherentes que cuando se gobierna para proteger intereses econ\u00f3micos, es imposible salvaguardar valores humanos como el medio ambiente. Sobre la importancia de la educaci\u00f3n, parte del problema es la desinformaci\u00f3n. La estrategia de gobernanza democr\u00e1tica es tratar de minar alternativas posibles a trav\u00e9s de desinformaci\u00f3n y el dogma, pero la educaci\u00f3n es el \u00fanico remedio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Al culminar las preguntas realizadas por estudiantes, se escogieron cuatro preguntas breves de la plataforma de Facebook Live para que cada panelista pudiera reaccionar y ofrecieran su opini\u00f3n:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\" type=\"1\"><li><strong>\u00bfLa democracia l\u00edquida debe ser la aspiraci\u00f3n de toda democracia contempor\u00e1nea?<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Joel I. Col<\/em><\/strong><strong><em>\u00f3n R\u00edos:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El principio detr\u00e1s de la idea de democracia l\u00edquida&nbsp;en el cual los ciudadanos&nbsp;tienen distintos intereses, ese principio es positivo porque se basa en la idea de que no existe en inter\u00e9s nacional. No necesariamente todo es bueno para todo el mundo. Cada cual debe tener derecho a participar en decisiones que afectan a uno mismo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s no funciona en todos los pa\u00edses, pero como principio lo considera algo positivo.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>\u00bfPor qu\u00e9 es que&nbsp;<em>Religious Right,&nbsp;<\/em>o derecha religiosa, es tan efectiva adquiriendo poder pol\u00edtico? \u00bfPor qu\u00e9 no hay un equivalente movimiento religioso de izquierda?<\/strong><em><\/em><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta<\/em><\/strong><strong><em>&nbsp;de Yanira Reyes Gil:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por un lado, si existen movimientos religiosos que no son de izquierda y muchos de esos movimientos se han visto en asuntos de luchas de pa\u00edses como, por ejemplo, en&nbsp;Centroam\u00e9rica&nbsp;como por ejemplo el grupo<em>&nbsp;Cat\u00f3licas por el Derecho a Decidi<\/em>r.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Puerto Rico hay agrupaciones religiosas que se han unido a luchas como por ejemplo cuando se estaba buscando que se aprobara Carta Circular sobre educaci\u00f3n con perspectiva de g\u00e9nero. Es por momentos que la derecha religiosa se puede aliar con sectores conservadores que tambi\u00e9n tienen en com\u00fan el mantener la sociedad sin avances de diferentes sectores.&nbsp;Pero la profesoraentiende que es coyuntural y que va cambiando con el tiempo.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>\u00bfPodr\u00eda definir su visi\u00f3n o definici\u00f3n del \u201cnuevo pueblo\u201d que no necesariamente es el concepto \u00e9tnico tradicional?<\/strong><em><\/em><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de&nbsp;<\/em><\/strong><strong><em>Joel I. Col\u00f3n R\u00edos:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El concepto de pueblo se construye. No es objetivo.<em>&nbsp;<\/em>En el pasado en S.XIX el pueblo eran los pobres, pero de igual forma el pueblo es la mayor\u00eda. Pero igualmente el pueblo puede ser un grupo \u00e9tnico en particular. Cuando un grupo de seres humanos que realmente son muy distintos, se comienzan a ver como seres humanos que tienen reclamos que solamente pueden solucionarse transformando de manera importante el sistema pol\u00edtico, en ese momento es que se construye un nuevo \u201cnosotros\u201d.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>El objetivo n\u00famero 16 de los desarrollos sostenibles de las Naciones Unidas establece como los conflictos, inseguridad, instituciones d\u00e9biles y el acceso limitado a la justicia contin\u00faan suponiendo una grave amenaza para el desarrollo sostenible. \u00bfPodr\u00eda ilustrarnos&nbsp;<\/strong><strong>c\u00f3mo&nbsp;los pa\u00edses est\u00e1n logrando este objetivo? Es decir, \u00bfc\u00f3mo el objetivo de desarrollo sostenible incide en la democracia global y por supuesto en nuestra democracia?&nbsp;<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Respuesta de Luis E. Rodr<\/em><\/strong><strong><em>\u00edguez Rivera:<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo sostenible es contradictorio. Lo que hace falta es una retirada sostenible. Tiene un enfoque sostenible. Nos lleva a&nbsp;hacer&nbsp;lo menos requerido. Los \u00edndices de progreso atados&nbsp;al crecimiento&nbsp;econ\u00f3mico perpet\u00faan condiciones econ\u00f3micas y mantienen realidad que lo que se valora es indicadores de crecimiento econ\u00f3mico y obvia otros como educaci\u00f3n, ambiente e igualdad. Lo que se discute en la academia es que se debe cuestionar este acercamiento e intentar adoptar medidas como las que adoptaron los pa\u00edses bajos, Noruega, Dinamarca, que han comenzado a ser innovadores.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p class=\"wp-block-paragraph\">* Estudiante de tercer a\u00f1o de la Escuela de Derecho de la Universidad de Puerto Rico y Editora Titular del Volumen XC de la Revista Jur\u00eddica de la UPR.<\/p>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Primer panel: Estado de la democracia, perspectiva global RESE\u00d1A Por: Giuliana Gonz\u00e1lez Espino* La Revista Jur\u00eddica de la Universidad de Puerto Rico llev\u00f3 a cabo el pasado 16 de febrero de 2021, el simposio virtual:&nbsp;Retos de la democracia puertorrique\u00f1a, el cual se dividi\u00f3 en conferencias de tres d\u00edas cada una con su respectivo panel de<\/p>\n<div class=\"read-more\"><a href=\"https:\/\/derecho.uprrp.edu\/inrev\/2021\/03\/16\/resenas-del-simposio-retos-de-la-democracia-puertorriquena\/\" title=\"Read More\">Read More<\/a><\/div>\n","protected":false},"author":23,"featured_media":2820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[46,84,96,116,122,133],"class_list":["post-2848","post","type-post","status-publish","format-standard","has-post-thumbnail","category-resenas","tag-democracia","tag-joel-colon-rios","tag-luis-rodriguez","tag-resena","tag-simposio","tag-yanira-reyes-gil"],"_links":{"self":[{"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/posts\/2848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/comments?post=2848"}],"version-history":[{"count":0,"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/posts\/2848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/media\/2820"}],"wp:attachment":[{"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/media?parent=2848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/categories?post=2848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/derecho.uprrp.edu\/inrev\/wp-json\/wp\/v2\/tags?post=2848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}